{"id":24859,"date":"2026-05-12T07:58:06","date_gmt":"2026-05-12T05:58:06","guid":{"rendered":"https:\/\/junkersaircraft.com\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/"},"modified":"2026-05-18T08:52:42","modified_gmt":"2026-05-18T06:52:42","slug":"zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers","status":"publish","type":"post","link":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/","title":{"rendered":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers"},"content":{"rendered":"<div class=\"gb-container gb-container-4e823d54\">\n\n<p class=\"wp-block-paragraph\">Hugo Junkers incarne encore aujourd\u2019hui l\u2019esprit d\u2019innovation, la vision technique et une alliance singuli\u00e8re entre art de l\u2019ing\u00e9nierie, design et esprit pionnier. Dans cet entretien, son arri\u00e8re-petite-fille Charlotte Junkers explique comment cet h\u00e9ritage marque son quotidien personnel et entrepreneurial \u2013 et pourquoi le nom Junkers repr\u00e9sente pour elle \u00e0 la fois une responsabilit\u00e9 et une source d\u2019inspiration. Il est question d\u2019avions historiques, de gestion de marque moderne, de nouveaux produits et de la mani\u00e8re de faire vivre la tradition sans perdre de vue l\u2019avenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Le nom Junkers est associ\u00e9 \u00e0 une port\u00e9e historique consid\u00e9rable. Comment cet h\u00e9ritage te marque-t-il personnellement \u2013 et dans quelle mesure fait-il consciemment partie de ton quotidien ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le contexte historique de ma famille m\u2019a certainement marqu\u00e9e davantage que je ne m\u2019en rendais compte au moment o\u00f9 cela se produisait. Par exemple, nous avons toujours \u00e9t\u00e9 une famille qui aimait beaucoup d\u00e9battre. \u00c0 table, avec mes fr\u00e8res et s\u0153urs et mes parents, il n\u2019y avait jamais de silence \u2013 exactement comme on le rapporte \u00e0 propos de Hugo Junkers, qui avait 12 enfants et \u00e9tait une personne \u00e0 la pens\u00e9e extr\u00eamement lib\u00e9rale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd\u2019hui, surtout dans le quotidien professionnel, l\u2019histoire de Hugo Junkers n\u2019est pas seulement perceptible en arri\u00e8re-plan, car c\u2019est son nom qui figure sur nos produits. Hugo Junkers \u00e9tait en avance sur son temps dans de nombreux domaines dont on peut encore s\u2019inspirer aujourd\u2019hui : la qualit\u00e9, la vision \u00e0 long terme, l\u2019esprit d\u2019\u00e9quipe, la force d\u2019innovation \u2026 En cas de doute, j\u2019aime parfois me demander : comment aurait-il fait ? Quels \u00e9taient ses principes, et pouvons-nous les transposer \u00e0 notre situation actuelle ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>En tant qu\u2019arri\u00e8re-petite-fille de Hugo Junkers, ressens-tu une exigence ou une pression particuli\u00e8re \u00e0 la hauteur de ce nom \u2013 notamment dans ton r\u00f4le de directrice g\u00e9n\u00e9rale ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Moins en tant qu\u2019arri\u00e8re-petite-fille. La pression est quelque chose qui n\u2019a jamais exist\u00e9 dans notre famille. Cela aussi remonte peut-\u00eatre \u00e0 Hugo Junkers et \u00e0 sa mani\u00e8re d\u2019aborder les gens avec respect et estime. En revanche, en ce qui concerne la marque Junkers en g\u00e9n\u00e9ral, je ressens bel et bien une grande responsabilit\u00e9. Je pense qu\u2019avec un tel nom, on ne peut pas faire simplement ce que l\u2019on veut. Le produit doit correspondre \u00e0 100 % aux principes de Hugo Junkers : r\u00e9pondre en permanence aux exigences les plus \u00e9lev\u00e9es gr\u00e2ce \u00e0 la qualit\u00e9 et, ainsi, servir durablement les personnes.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-ddb8e106\">\n\n<p class=\"wp-block-paragraph\"><strong><em>Les avions en m\u00e9tal l\u00e9ger Junkers \u00e9taient tr\u00e8s en avance sur leur temps sur le plan technique. Qu\u2019est-ce qui te fascine personnellement le plus dans cette histoire d\u2019innovation ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hugo Junkers a toujours eu une vision. C\u2019\u00e9tait une chose. Il \u00e9tait tout simplement capable de penser plus loin que beaucoup d\u2019autres, parce qu\u2019il n\u2019acceptait aucune limite. Mais surtout, il savait aussi identifier et encourager des personnes hautement comp\u00e9tentes, et cr\u00e9er un environnement leur permettant d\u2019atteindre les performances exceptionnelles n\u00e9cessaires pour concr\u00e9tiser une telle force d\u2019innovation.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-512d98ae\">\n\n<p class=\"wp-block-paragraph\"><strong><em>Quel r\u00f4le concret nos avions jouent-ils aujourd\u2019hui dans l\u2019identit\u00e9 globale de la marque Junkers ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils en incarnent le noyau le plus profond. Ils repr\u00e9sentent tout ce que Junkers souhaite incarner : le vol dans sa plus belle forme, \u00e0 la pointe de la technologie et, sur le plan esth\u00e9tique, toujours in\u00e9gal\u00e9 aujourd\u2019hui. Il n\u2019existe pas d\u2019avion plus beau dans cette cat\u00e9gorie, et les avions Junkers sont en outre parfaits sur les plans technique et qualitatif. Ils voient le jour gr\u00e2ce \u00e0 une \u00e9quipe formidable, dans une manufacture impressionnante, et ont le potentiel d\u2019enthousiasmer toutes sortes de personnes \u2013 que ce soit pour l\u2019aviation, l\u2019histoire ou le design.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-0eead2a3\">\n\n<p class=\"wp-block-paragraph\"><em><strong>Selon toi, qui s\u2019enthousiasme aujourd\u2019hui pour la marque Junkers Aircraft \u2013 et qu\u2019est-ce qui attire particuli\u00e8rement ces personnes ?<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce qui est fascinant, c\u2019est que des personnes tr\u00e8s diff\u00e9rentes s\u2019enthousiasment pour les avions Junkers. Les pilotes qui suivent le march\u00e9 des ULM, bien s\u00fbr. Ils ont naturellement tout de suite remarqu\u00e9 qu\u2019il \u00e9tait apparu quelque chose de v\u00e9ritablement unique dans sa cat\u00e9gorie. Mais cela attire aussi d\u2019autres personnes \u2013 des personnes qui, auparavant, ne s\u2019int\u00e9ressaient peut-\u00eatre pas du tout \u00e0 l\u2019aviation, mais qui ont simplement un \u0153il pour le design et la technologie, et peut-\u00eatre aussi un certain int\u00e9r\u00eat pour la riche histoire qui se cache derri\u00e8re les avions Junkers, pionniers de l\u2019aviation civile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Junkers incarne une tradition tr\u00e8s forte. Quels march\u00e9s te semblent actuellement particuli\u00e8rement int\u00e9ressants \u2013 notamment en ce qui concerne l\u2019int\u00e9r\u00eat pour l\u2019ing\u00e9nierie allemande et l\u2019histoire de l\u2019aviation ?<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9alit\u00e9, il n\u2019y a pratiquement pas d\u2019exceptions. L\u2019important est que nous racontions la bonne histoire : \u00e0 savoir que Junkers est synonyme d\u2019aviation civile. Lorsque la Seconde Guerre mondiale a \u00e9clat\u00e9 et que des avions de combat ont \u00e9t\u00e9 d\u00e9velopp\u00e9s et construits, Hugo Junkers avait d\u00e9j\u00e0 \u00e9t\u00e9 expropri\u00e9 et \u00e9tait d\u00e9c\u00e9d\u00e9. Hugo Junkers incarne l\u2019ing\u00e9nierie allemande du d\u00e9but du XXe si\u00e8cle, une \u00e9poque o\u00f9 l\u2019Allemagne d\u00e9ployait une force d\u2019innovation extraordinaire. Bien s\u00fbr, cela ne concernait pas seulement Junkers, mais dans l\u2019aviation, il a longtemps \u00e9t\u00e9 une figure dominante gr\u00e2ce \u00e0 ses avions m\u00e9talliques. Cette histoire est nouvelle et int\u00e9ressante pour beaucoup de personnes, o\u00f9 qu\u2019elles se trouvent dans le monde. On peut facilement et rapidement s\u2019identifier \u00e0 Junkers lorsque l\u2019on s\u2019int\u00e9resse \u00e0 l\u2019un de ces th\u00e8mes : l\u2019aviation, la technique en g\u00e9n\u00e9ral ou le design. Partout dans le monde.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-909d5a64\">\n\n<p class=\"wp-block-paragraph\"><em><strong>Quels \u00e9l\u00e9ments esth\u00e9tiques ou conceptuels de vos montres reprennent consciemment l\u2019esth\u00e9tique ou la technologie des avions historiques ?<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eh bien, une montre est ronde et poss\u00e8de deux aiguilles ou plus. Les instruments de bord constituent donc une r\u00e9f\u00e9rence \u00e9vidente, puisqu\u2019autrefois ils \u00e9taient tous ronds et devaient \u00eatre parfaitement lisibles. Pour nos montres d\u2019aviateur, nous nous inspirons fortement de ce principe. Comme caract\u00e9ristique esth\u00e9tique \u00e0 part enti\u00e8re, toutes nos montres argent\u00e9es, ainsi que de nombreux mod\u00e8les color\u00e9s ou noirs, poss\u00e8dent un cadran effet t\u00f4le ondul\u00e9e, ce qui rend encore plus imm\u00e9diat le fait de porter Junkers et la passion du vol au poignet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Selon toi, comment la marque Junkers Aircraft doit-elle se positionner pour rester innovante sans pour autant perdre son identit\u00e9 historique ?<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce n\u2019est pas du tout une contradiction, bien au contraire. Si l\u2019identit\u00e9 historique signifie agir selon les principes de Hugo Junkers et de son entreprise, alors l\u2019innovation est la seule voie possible. Hugo Junkers a travaill\u00e9 toute sa vie sur de nouvelles id\u00e9es. L\u2019A60, \u00e9volution de l\u2019A50, en est un exemple concret. L\u2019A60 est un ULM haut de gamme qui se distingue de tous les autres ULM c\u00f4te \u00e0 c\u00f4te par son esth\u00e9tique et sa qualit\u00e9. Et ce n\u2019est pas tout : il poss\u00e8de un pare-brise amovible, qui permet de transformer l\u2019avion en cabriolet !<\/p>\n\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Tu as r\u00e9cemment ouvert un showroom \u00e0 Munich. Quel r\u00f4le joue un lieu physique de ce type dans la mise en sc\u00e8ne globale de la marque Junkers ?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je me sens moi-m\u00eame presque comme une native du num\u00e9rique. \u00c0 la maison, j\u2019en ai assur\u00e9ment deux. Mais m\u00eame eux, lorsqu\u2019il y a quelque chose de particulier \u00e0 d\u00e9couvrir et \u00e9ventuellement \u00e0 acheter, se d\u00e9placent et veulent le vivre, le toucher, l\u2019essayer. Dans notre showroom, nous souhaitons transmettre l\u2019atmosph\u00e8re Junkers et permettre aux gens de ressentir de pr\u00e8s l\u2019enthousiasme pour Junkers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hugo Junkers incarne encore aujourd\u2019hui l\u2019esprit d\u2019innovation, la vision technique et une alliance singuli\u00e8re entre art de l\u2019ing\u00e9nierie, design et esprit pionnier. Dans cet entretien, son arri\u00e8re-petite-fille Charlotte Junkers explique comment cet h\u00e9ritage marque son quotidien personnel et entrepreneurial \u2013 et pourquoi le nom Junkers repr\u00e9sente pour elle \u00e0 la fois une responsabilit\u00e9 et une &#8230; <a title=\"Entre tradition et aviation moderne : entretien avec Charlotte Junkers\" class=\"read-more\" href=\"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/\" aria-label=\"En savoir plus sur Entre tradition et aviation moderne : entretien avec Charlotte Junkers\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":24853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[70],"tags":[],"class_list":["post-24859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers\" \/>\n<meta property=\"og:description\" content=\"Hugo Junkers incarne encore aujourd\u2019hui l\u2019esprit d\u2019innovation, la vision technique et une alliance singuli\u00e8re entre art de l\u2019ing\u00e9nierie, design et esprit pionnier. Dans cet entretien, son arri\u00e8re-petite-fille Charlotte Junkers explique comment cet h\u00e9ritage marque son quotidien personnel et entrepreneurial \u2013 et pourquoi le nom Junkers repr\u00e9sente pour elle \u00e0 la fois une responsabilit\u00e9 et une ... Weiterlesen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/\" \/>\n<meta property=\"og:site_name\" content=\"Junkers\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T05:58:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T06:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pp.admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"pp.admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/\"},\"author\":{\"name\":\"pp.admin\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#\\\/schema\\\/person\\\/c83103cd858b846f1f94cf0b855932d9\"},\"headline\":\"Entre tradition et aviation moderne : entretien avec Charlotte Junkers\",\"datePublished\":\"2026-05-12T05:58:06+00:00\",\"dateModified\":\"2026-05-18T06:52:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/\"},\"wordCount\":1330,\"publisher\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/260416_100Y_LC_Event_131.jpg\",\"articleSection\":[\"Non cat\u00e9goris\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/\",\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/\",\"name\":\"Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/260416_100Y_LC_Event_131.jpg\",\"datePublished\":\"2026-05-12T05:58:06+00:00\",\"dateModified\":\"2026-05-18T06:52:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/260416_100Y_LC_Event_131.jpg\",\"contentUrl\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/260416_100Y_LC_Event_131.jpg\",\"width\":6757,\"height\":4507,\"caption\":\"100 Jahre Feier Luftahnsa LC Event im Hangar One in Frankfurt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/2026\\\/05\\\/12\\\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entre tradition et aviation moderne : entretien avec Charlotte Junkers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#website\",\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/\",\"name\":\"Junkers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/junkersaircraft.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#organization\",\"name\":\"Junkers\",\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/junkers-logo-white-new.svg\",\"contentUrl\":\"https:\\\/\\\/junkersaircraft.com\\\/wp-content\\\/uploads\\\/junkers-logo-white-new.svg\",\"caption\":\"Junkers\"},\"image\":{\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/junkersaircraft.com\\\/#\\\/schema\\\/person\\\/c83103cd858b846f1f94cf0b855932d9\",\"name\":\"pp.admin\",\"sameAs\":[\"http:\\\/\\\/junkersaircraft.com\"],\"url\":\"https:\\\/\\\/junkersaircraft.com\\\/fr\\\/author\\\/pp-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/","og_locale":"fr_FR","og_type":"article","og_title":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers","og_description":"Hugo Junkers incarne encore aujourd\u2019hui l\u2019esprit d\u2019innovation, la vision technique et une alliance singuli\u00e8re entre art de l\u2019ing\u00e9nierie, design et esprit pionnier. Dans cet entretien, son arri\u00e8re-petite-fille Charlotte Junkers explique comment cet h\u00e9ritage marque son quotidien personnel et entrepreneurial \u2013 et pourquoi le nom Junkers repr\u00e9sente pour elle \u00e0 la fois une responsabilit\u00e9 et une ... Weiterlesen ...","og_url":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/","og_site_name":"Junkers","article_published_time":"2026-05-12T05:58:06+00:00","article_modified_time":"2026-05-18T06:52:42+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131-1024x683.jpg","type":"image\/jpeg"}],"author":"pp.admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"pp.admin","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#article","isPartOf":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/"},"author":{"name":"pp.admin","@id":"https:\/\/junkersaircraft.com\/#\/schema\/person\/c83103cd858b846f1f94cf0b855932d9"},"headline":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers","datePublished":"2026-05-12T05:58:06+00:00","dateModified":"2026-05-18T06:52:42+00:00","mainEntityOfPage":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/"},"wordCount":1330,"publisher":{"@id":"https:\/\/junkersaircraft.com\/#organization"},"image":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#primaryimage"},"thumbnailUrl":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131.jpg","articleSection":["Non cat\u00e9goris\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/","url":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/","name":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers - Junkers","isPartOf":{"@id":"https:\/\/junkersaircraft.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#primaryimage"},"image":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#primaryimage"},"thumbnailUrl":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131.jpg","datePublished":"2026-05-12T05:58:06+00:00","dateModified":"2026-05-18T06:52:42+00:00","breadcrumb":{"@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#primaryimage","url":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131.jpg","contentUrl":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/260416_100Y_LC_Event_131.jpg","width":6757,"height":4507,"caption":"100 Jahre Feier Luftahnsa LC Event im Hangar One in Frankfurt"},{"@type":"BreadcrumbList","@id":"https:\/\/junkersaircraft.com\/fr\/2026\/05\/12\/zwischen-tradition-und-moderner-luftfahrt-interview-mit-charlotte-junkers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/junkersaircraft.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Entre tradition et aviation moderne : entretien avec Charlotte Junkers"}]},{"@type":"WebSite","@id":"https:\/\/junkersaircraft.com\/#website","url":"https:\/\/junkersaircraft.com\/","name":"Junkers","description":"","publisher":{"@id":"https:\/\/junkersaircraft.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/junkersaircraft.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/junkersaircraft.com\/#organization","name":"Junkers","url":"https:\/\/junkersaircraft.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/junkersaircraft.com\/#\/schema\/logo\/image\/","url":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/junkers-logo-white-new.svg","contentUrl":"https:\/\/junkersaircraft.com\/wp-content\/uploads\/junkers-logo-white-new.svg","caption":"Junkers"},"image":{"@id":"https:\/\/junkersaircraft.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/junkersaircraft.com\/#\/schema\/person\/c83103cd858b846f1f94cf0b855932d9","name":"pp.admin","sameAs":["http:\/\/junkersaircraft.com"],"url":"https:\/\/junkersaircraft.com\/fr\/author\/pp-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/posts\/24859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/comments?post=24859"}],"version-history":[{"count":21,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/posts\/24859\/revisions"}],"predecessor-version":[{"id":25038,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/posts\/24859\/revisions\/25038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/media\/24853"}],"wp:attachment":[{"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/media?parent=24859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/categories?post=24859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/junkersaircraft.com\/fr\/wp-json\/wp\/v2\/tags?post=24859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}